{"id":27975,"date":"2026-09-02T06:36:15","date_gmt":"2026-09-02T10:36:15","guid":{"rendered":"https:\/\/belacereais.com.br\/2026\/milho\/milho-inicia-setembro-em-alta-nos-contratos-futuros\/"},"modified":"2026-09-02T06:36:15","modified_gmt":"2026-09-02T10:36:15","slug":"milho-inicia-setembro-em-alta-nos-contratos-futuros","status":"publish","type":"post","link":"https:\/\/belacereais.com.br\/en\/2026\/milho\/milho-inicia-setembro-em-alta-nos-contratos-futuros\/","title":{"rendered":"Corn futures contracts start September higher."},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/www.agrolink.com.br\/upload\/imagens-resizes\/cd9e972381b64ffe80f68a69cd7d4713_858x483.jpg\" \/><\/p>\n<div class=\"section-description section-description-noticias mt-3\">\n<p>The market of <a href=\"https:\/\/www.agrolink.com.br\/culturas\/milho?utm_source=agrolink-detalhe-noticia&amp;utm_medium=detalhe-noticia&amp;utm_campaign=links-internos%09\" target=\"_blank\" rel=\"noopener\">corn<\/a> come\u00e7ou setembro com valoriza\u00e7\u00e3o nos contratos futuros e negocia\u00e7\u00f5es ainda seletivas no mercado f\u00edsico, em um cen\u00e1rio de suporte vindo do exterior e de oferta mais contida em algumas regi\u00f5es. Segundo a TF Agroecon\u00f4mica, a alta global do cereal, associada \u00e0 perspectiva de redu\u00e7\u00e3o da safra dos Estados Unidos e de quebra na Europa, abriu espa\u00e7o para o <a href=\"https:\/\/www.agrolink.com.br\/culturas\/milho?utm_source=agrolink-detalhe-noticia&amp;utm_medium=detalhe-noticia&amp;utm_campaign=links-internos%09\" target=\"_blank\" rel=\"noopener\">corn<\/a> brasileiro e ajudou a sustentar os pre\u00e7os futuros na B3.\n<\/p>\n<div id=\"agk_14000_pos_3_sidebar_mobile\" style=\"text-align: center;\" class=\"mb-4\">\n<\/div>\n<div id=\"agk_14000_pos_4_conteudo_desktop\" style=\"text-align: center;\" class=\"d-none d-lg-block mb-md-4\">\n<\/div>\n<p>Na ter\u00e7a-feira, o contrato setembro\/26 fechou a R$ 72,18, alta de R$ 1,12 no dia. Novembro\/26 terminou a R$ 78,43, avan\u00e7o de R$ 0,83, enquanto janeiro\/27 encerrou a R$ 81,79, ganho de R$ 0,90. No Rio Grande do Sul, as indica\u00e7\u00f5es ficaram entre R$ 58 e R$ 65 por saca, com liquidez restrita e produtores mais seletivos. O pre\u00e7o m\u00e9dio estadual avan\u00e7ou 1,53% na semana, para R$ 60,23.<\/p>\n<p>Em Santa Catarina, as refer\u00eancias de venda permanecem pr\u00f3ximas de R$ 60 por saca, diante de demanda ao redor de R$ 55. O estado mant\u00e9m forte depend\u00eancia de milho de outras regi\u00f5es, j\u00e1 que consome cerca de 8,5 milh\u00f5es de toneladas ao ano e produziu 2,67 milh\u00f5es na safra 2025\/26. O Paraguai aparece como alternativa de abastecimento.\n<\/p>\n<div id=\"agk_14000_pos_4_conteudo_mobile\" style=\"text-align: center;\" class=\"mb-4\">\n<\/div>\n<div id=\"agk_14000_pos_5_conteudo_desktop\" style=\"text-align: center;\" class=\"d-none d-lg-block mb-md-4\">\n<\/div>\n<p>No Paran\u00e1, as negocia\u00e7\u00f5es seguem pontuais, com indica\u00e7\u00f5es perto de R$ 60 e demanda em torno de R$ 55 por saca CIF. O pre\u00e7o recebido pelo produtor chegou a R$ 56,79, alta de 7,8% sobre a m\u00e9dia de julho e de 11% frente a agosto de 2025. A colheita da segunda safra alcan\u00e7ou 83% da \u00e1rea, enquanto o plantio da primeira safra 2026\/27 chegou a 6%.<\/p>\n<p>Em Mato Grosso do Sul, as cota\u00e7\u00f5es variam entre R$ 50 e R$ 55 por saca. A demanda da ind\u00fastria de bioenergia segue firme e ajuda a absorver a oferta, enquanto a colheita da segunda safra atingiu 88% da \u00e1rea.<\/p>\n<p>\n\u00a0<\/p>\n<\/p><\/div>\n<h6><em>THE <strong>Bela Cereais<\/strong> works with the best grains on the market and also keeps you up to date with the latest news and analyses on agribusiness.<br \/>\nDon&#039;t forget to follow our social networks.<\/em><\/h6>\n<p><a href=\"https:\/\/www.agrolink.com.br\/noticias\/milho-inicia-setembro-em-alta-nos-contratos-futuros_518440.html\" target=\"_blank\" rel=\"noopener\">Access News Source <\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>O mercado de milho come\u00e7ou setembro com valoriza\u00e7\u00e3o nos contratos futuros e negocia\u00e7\u00f5es ainda seletivas&hellip;<\/p>","protected":false},"author":1,"featured_media":27793,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[223],"tags":[244,248,255,249,254,250,246,247,256,245,253,252,251],"class_list":["post-27975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-milho","tag-agrolink","tag-agrotoxicos","tag-artigos-tecnicos","tag-classificados","tag-colunistas","tag-compra","tag-cotacoes","tag-defensivos","tag-eventos","tag-noticias","tag-precos-agricolas","tag-previsao-do-tempo","tag-venda"],"_links":{"self":[{"href":"https:\/\/belacereais.com.br\/en\/wp-json\/wp\/v2\/posts\/27975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/belacereais.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/belacereais.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/belacereais.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/belacereais.com.br\/en\/wp-json\/wp\/v2\/comments?post=27975"}],"version-history":[{"count":0,"href":"https:\/\/belacereais.com.br\/en\/wp-json\/wp\/v2\/posts\/27975\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/belacereais.com.br\/en\/wp-json\/wp\/v2\/media\/27793"}],"wp:attachment":[{"href":"https:\/\/belacereais.com.br\/en\/wp-json\/wp\/v2\/media?parent=27975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/belacereais.com.br\/en\/wp-json\/wp\/v2\/categories?post=27975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/belacereais.com.br\/en\/wp-json\/wp\/v2\/tags?post=27975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}